{"id":74212,"date":"2023-11-14T15:27:22","date_gmt":"2023-11-14T20:27:22","guid":{"rendered":"https:\/\/www.agribusinessglobal.com\/?p=74212"},"modified":"2023-11-15T11:05:32","modified_gmt":"2023-11-15T16:05:32","slug":"fluroxypyr-expansion-here-to-stay-requires-stewardship","status":"publish","type":"post","link":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/","title":{"rendered":"La expansi\u00f3n del fluroxipir lleg\u00f3 para quedarse y requiere gesti\u00f3n"},"content":{"rendered":"<p>Fluroxipir es un importante ingrediente activo herbicida del Grupo 4 que se introdujo a principios de los a\u00f1os 1980. Comercializado inicialmente como Starane por Dow, este ingrediente activo se ha utilizado ampliamente en cultivos de cereales y gram\u00edneas debido a su seguridad para el cultivo, su idoneidad para mezclas y su alto nivel de actividad sobre la kochia.<\/p>\n<p>En los EE. UU., el fluroxipir est\u00e1 etiquetado en el trigo, la cebada, el ma\u00edz, el sorgo en grano y los pastos. Un testimonio de su flexibilidad, el fluroxipir se encuentra en premezclas con la mayor\u00eda de los herbicidas populares para pastos y hojas anchas que se usan en el trigo. Fluroxipir tambi\u00e9n mejora la eficacia de las mezclas de herbicidas de hoja ancha cuando se atacan malezas como sericea lespedeza e hinojo en pastos, as\u00ed como tr\u00e9bol y pl\u00e1tano en c\u00e9sped.<\/p>\n<p><a href=\"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/how-kochia-became-resistant-to-glyphosate\/\">Kochia<\/a> sigue estando entre las malezas de hoja ancha m\u00e1s dif\u00edciles en las regiones de llanuras y praderas de EE. UU. y Canad\u00e1, y existen relativamente pocos herbicidas eficaces para la kochia que puedan usarse de manera segura en postemergencia en el trigo. Por ejemplo, <a href=\"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/is-the-u-s-already-headed-for-dicamba-resistant-weeds\/\">dicamba<\/a>, que es muy activo sobre la kochia, generalmente se considera demasiado da\u00f1ino para usarse en dosis efectivas para la kochia cuando se aplica en postemergencia en el trigo.<\/p>\n<p>El bromoxinil es un herbicida de trigo de hoja ancha muy eficaz, pero debido a su naturaleza de contacto, requiere que se roc\u00eden la kochia y otras malezas cuando son relativamente peque\u00f1as. La naturaleza sistem\u00e1tica del fluroxipir lo ha convertido en una herramienta valiosa para los productores de trigo que cultivan kochia, ya que a menudo se enfrentan al tratamiento de campos extensos donde puede resultar dif\u00edcil realizar aplicaciones oportunas cuando las malezas son peque\u00f1as.<\/p>\n<p>El problema es generalizado a medida que la kochia, que es una maleza com\u00fan desde la pen\u00ednsula de Texas hasta las llanuras de EE. UU., contin\u00faa hacia el norte hasta las provincias de las praderas de Canad\u00e1. Si bien hist\u00f3ricamente ha sido un problema en las zonas donde se cultiva trigo, tambi\u00e9n infesta las \u00e1reas occidentales de producci\u00f3n de ma\u00edz y soja. De manera similar, el uso principal del fluroxipir ha sido en granos peque\u00f1os, aunque m\u00e1s recientemente se ha convertido en una herramienta importante en el sorgo en grano, el ma\u00edz extensivo y las geograf\u00edas en barbecho donde se encuentra la kochia.<\/p>\n<p>La extensi\u00f3n de la kochia y la importancia del fluroxipir se reflejan en datos de mercado recientes que muestran que el valor de las aplicaciones de herbicidas a base de fluroxipir ha aumentado de 27% de 2020 a 2022. Las ventas minoristas totales de herbicidas que contienen fluroxipir aumentaron m\u00e1s de 14% este a\u00f1o en septiembre de 2023. De manera similar, los registros de importaci\u00f3n de fluroxipir muestran un crecimiento muy fuerte en los \u00faltimos cinco a\u00f1os, subiendo m\u00e1s de 400%.<\/p>\n<p>Dada la importancia del fluroxipir para los agricultores de EE. UU. y Canad\u00e1, la gesti\u00f3n del producto y la resistencia ser\u00e1n fundamentales. Se han identificado poblaciones de Kochia resistentes al fluroxipir en \u00e1reas productoras de trigo tanto de EE. UU. como de Canad\u00e1. La aparici\u00f3n de biotipos de kochia resistentes al fluroxipir se suma al crecimiento de poblaciones de kochia resistentes tambi\u00e9n a la ELA, el glifosato y la dicamba.<\/p>\n<p>Si bien es evidente un auge en las aplicaciones de fluroxipir, tambi\u00e9n es una advertencia. Utilizar premezclas y mezclas de tanque efectivas, mantener tasas y tiempos de aplicaci\u00f3n correctos y rotar y utilizar nuevos qu\u00edmicos, como Duplosan* (diclorprop-p) de <a href=\"https:\/\/nufarm.com\/\" target=\"_blank\" rel=\"noopener\">Nufarm<\/a>, para ayudar a abordar la resistencia de las malezas y mantener la eficacia y el valor del fluroxipir.<\/p>\n<h2><em>Algunas de las mezclas de herbicidas m\u00e1s comunes que contienen fluroxipir.<\/em><\/h2>\n<table style=\"border-collapse: collapse;width: 100%\">\n<tbody>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\"><strong>Producto<\/strong><\/td>\n<td style=\"width: 33.2814%\" width=\"156\"><strong>Fabricante<\/strong><\/td>\n<td style=\"width: 33.2814%\" width=\"258\"><strong>Ingredientes activos<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">estrella axial<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Syngenta<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + pinoxaden<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">Husky FX<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Bayer<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + pirasulfatol + bromoxinilo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">WideMatch\/Truslate<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Corteva\/Nufarm<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + clopiralida<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">Starane NXT<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Corteva<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + bromoxinilo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">Quemar<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Nufarm<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + dicamba + 2,4-D<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">Carn\u00edvoro \/ Limpiador M<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Winfield United \/ Nufarm<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + bromoxinilo + MCPA<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">Kochiavore \/ Limpieza limpia D<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Winfield United \/ Nufarm<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + bromoxinilo + 2,4-D<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2814%\" width=\"156\">orocielo<\/td>\n<td style=\"width: 33.2814%\" width=\"156\">Corteva<\/td>\n<td style=\"width: 33.2814%\" width=\"258\">Fluroxipir + florasulam + piroxsulam<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*<em>Duplosan es una marca comercial de Nufarm y est\u00e1 registrada para su uso en Canad\u00e1 para granos peque\u00f1os y uso previo a la siembra, y est\u00e1 pendiente de registro en EE. UU. para granos peque\u00f1os, antes de la siembra y en barbecho.<\/em><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Un testimonio de su flexibilidad, el fluroxipir se encuentra en premezclas con la mayor\u00eda de los herbicidas populares para pastos y hojas anchas que se usan en el trigo.<\/p>","protected":false},"author":112,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,19],"tags":[1919],"class_list":["post-74212","post","type-post","status-publish","format-standard","hentry","category-agrochemicals","category-herbicides","tag-fluroxypyr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fluroxypyr Expansion Here to Stay, Requires Stewardship - AgriBusiness Global<\/title>\n<meta name=\"description\" content=\"A testimony to its flexibility, fluroxypyr is found in premixes with most of the popular grass and broadleaf herbicides used in wheat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fluroxypyr Expansion Here to Stay, Requires Stewardship - AgriBusiness Global\" \/>\n<meta property=\"og:description\" content=\"A testimony to its flexibility, fluroxypyr is found in premixes with most of the popular grass and broadleaf herbicides used in wheat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/\" \/>\n<meta property=\"og:site_name\" content=\"AgriBusiness Global\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T20:27:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-15T16:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.agribusinessglobal.com\/wp-content\/themes\/AgribusinessTheme\/images\/ABG-Web-No-Feature-Logo.jpg\" \/>\n<meta name=\"author\" content=\"Dan Jacobs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.agribusinessglobal.com\/wp-content\/themes\/AgribusinessTheme\/images\/ABG-Web-No-Feature-Logo.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan Jacobs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/\"},\"author\":{\"name\":\"Dan Jacobs\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#\\\/schema\\\/person\\\/bfdcb3ede991793b939f75ca29b77658\"},\"headline\":\"Fluroxypyr Expansion Here to Stay, Requires Stewardship\",\"datePublished\":\"2023-11-14T20:27:22+00:00\",\"dateModified\":\"2023-11-15T16:05:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#organization\"},\"keywords\":[\"fluroxypyr\"],\"articleSection\":[\"Agrochemicals\",\"Herbicides\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/\",\"url\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/\",\"name\":\"Fluroxypyr Expansion Here to Stay, Requires Stewardship - AgriBusiness Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#website\"},\"datePublished\":\"2023-11-14T20:27:22+00:00\",\"dateModified\":\"2023-11-15T16:05:32+00:00\",\"description\":\"A testimony to its flexibility, fluroxypyr is found in premixes with most of the popular grass and broadleaf herbicides used in wheat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/agrochemicals\\\/herbicides\\\/fluroxypyr-expansion-here-to-stay-requires-stewardship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fluroxypyr Expansion Here to Stay, Requires Stewardship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/\",\"name\":\"AgriBusiness Global\",\"description\":\"Empowering Agriculture to Feed the World\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#organization\",\"name\":\"AgriBusiness Global\",\"url\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d6kq167ddwbdq.cloudfront.net\\\/farmchemint\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ABG-logo-250x150px-01.png\",\"contentUrl\":\"https:\\\/\\\/d6kq167ddwbdq.cloudfront.net\\\/farmchemint\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/ABG-logo-250x150px-01.png\",\"width\":251,\"height\":151,\"caption\":\"AgriBusiness Global\"},\"image\":{\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/pt\\\/#\\\/schema\\\/person\\\/bfdcb3ede991793b939f75ca29b77658\",\"name\":\"Dan Jacobs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g\",\"caption\":\"Dan Jacobs\"},\"url\":\"https:\\\/\\\/www.agribusinessglobal.com\\\/es\\\/author\\\/jacobs\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La expansi\u00f3n del fluroxipir lleg\u00f3 para quedarse y requiere administraci\u00f3n - AgriBusiness Global","description":"Un testimonio de su flexibilidad, el fluroxipir se encuentra en premezclas con la mayor\u00eda de los herbicidas populares para pastos y hojas anchas que se usan en el trigo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/","og_locale":"es_MX","og_type":"article","og_title":"Fluroxypyr Expansion Here to Stay, Requires Stewardship - AgriBusiness Global","og_description":"A testimony to its flexibility, fluroxypyr is found in premixes with most of the popular grass and broadleaf herbicides used in wheat.","og_url":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/","og_site_name":"AgriBusiness Global","article_published_time":"2023-11-14T20:27:22+00:00","article_modified_time":"2023-11-15T16:05:32+00:00","og_image":[{"url":"https:\/\/www.agribusinessglobal.com\/wp-content\/themes\/AgribusinessTheme\/images\/ABG-Web-No-Feature-Logo.jpg","type":"","width":"","height":""}],"author":"Dan Jacobs","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.agribusinessglobal.com\/wp-content\/themes\/AgribusinessTheme\/images\/ABG-Web-No-Feature-Logo.jpg","twitter_misc":{"Escrito por":"Dan Jacobs","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/#article","isPartOf":{"@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/"},"author":{"name":"Dan Jacobs","@id":"https:\/\/www.agribusinessglobal.com\/pt\/#\/schema\/person\/bfdcb3ede991793b939f75ca29b77658"},"headline":"Fluroxypyr Expansion Here to Stay, Requires Stewardship","datePublished":"2023-11-14T20:27:22+00:00","dateModified":"2023-11-15T16:05:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/www.agribusinessglobal.com\/pt\/#organization"},"keywords":["fluroxypyr"],"articleSection":["Agrochemicals","Herbicides"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/","url":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/","name":"La expansi\u00f3n del fluroxipir lleg\u00f3 para quedarse y requiere administraci\u00f3n - AgriBusiness Global","isPartOf":{"@id":"https:\/\/www.agribusinessglobal.com\/pt\/#website"},"datePublished":"2023-11-14T20:27:22+00:00","dateModified":"2023-11-15T16:05:32+00:00","description":"Un testimonio de su flexibilidad, el fluroxipir se encuentra en premezclas con la mayor\u00eda de los herbicidas populares para pastos y hojas anchas que se usan en el trigo.","breadcrumb":{"@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.agribusinessglobal.com\/es\/agrochemicals\/herbicides\/fluroxypyr-expansion-here-to-stay-requires-stewardship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.agribusinessglobal.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Fluroxypyr Expansion Here to Stay, Requires Stewardship"}]},{"@type":"WebSite","@id":"https:\/\/www.agribusinessglobal.com\/pt\/#website","url":"https:\/\/www.agribusinessglobal.com\/pt\/","name":"AgriBusiness Global","description":"Empoderar a la agricultura para alimentar al mundo","publisher":{"@id":"https:\/\/www.agribusinessglobal.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.agribusinessglobal.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.agribusinessglobal.com\/pt\/#organization","name":"AgriBusiness Global","url":"https:\/\/www.agribusinessglobal.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.agribusinessglobal.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/d6kq167ddwbdq.cloudfront.net\/farmchemint\/wp-content\/uploads\/2024\/06\/ABG-logo-250x150px-01.png","contentUrl":"https:\/\/d6kq167ddwbdq.cloudfront.net\/farmchemint\/wp-content\/uploads\/2024\/06\/ABG-logo-250x150px-01.png","width":251,"height":151,"caption":"AgriBusiness Global"},"image":{"@id":"https:\/\/www.agribusinessglobal.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.agribusinessglobal.com\/pt\/#\/schema\/person\/bfdcb3ede991793b939f75ca29b77658","name":"Dan Jacobs","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/secure.gravatar.com\/avatar\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cae6ef1abdee07eba3d4076990763c13e7a0ac8f9aebf0bd52973d60f7c0a86c?s=96&d=mm&r=g","caption":"Dan Jacobs"},"url":"https:\/\/www.agribusinessglobal.com\/es\/author\/jacobs\/"}]}},"acf":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paA6y4-jiY","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/posts\/74212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/comments?post=74212"}],"version-history":[{"count":0,"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/posts\/74212\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/media?parent=74212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/categories?post=74212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agribusinessglobal.com\/es\/wp-json\/wp\/v2\/tags?post=74212"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}